{"id":36102,"date":"2017-11-15T14:25:42","date_gmt":"2017-11-15T14:25:42","guid":{"rendered":"https:\/\/yogurtnest.com\/la-tribo-yogurtnest\/"},"modified":"2019-04-24T15:50:48","modified_gmt":"2019-04-24T15:50:48","slug":"la-tribo-yogurtnest","status":"publish","type":"page","link":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/","title":{"rendered":"La Tribo YogurtNest"},"content":{"rendered":"<p>[et_pb_section bb_built=&#8221;1&#8243; background_color=&#8221;#2ea3f2&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;3.0.47&#8243;][et_pb_fullwidth_header title=&#8221;A Tribo YogurtNest&#8221; subhead=&#8221;Fazes parte?&#8221; background_layout=&#8221;dark&#8221; _builder_version=&#8221;3.0.87&#8243; background_image=&#8221;https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/comunidade.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;on&#8221; max_width_tablet=&#8221;50px&#8221; \/][\/et_pb_section][et_pb_section bb_built=&#8221;1&#8243; _builder_version=&#8221;3.0.47&#8243;][et_pb_row _builder_version=&#8221;3.0.47&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text _builder_version=&#8221;3.0.87&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>Se amas o Planeta Terra e tentas fazer a tua parte para o manter nas melhores condi\u00e7\u00f5es; se amas a vida e tentas viv\u00ea-la plenamente; se te preocupas com a qualidade da tua alimenta\u00e7\u00e3o; se gostas de fazer as tuas coisas, com as tuas m\u00e3os, tu fazes parte da tribo YogurtNest!<\/p>\n<p>Neste cantinho do yogurtnest.com, conhecer\u00e1s alguns dos nossos campe\u00f5es, que promovem os valores do YogurtNest atrav\u00e9s do seu trabalho e actividades.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row make_equal=&#8221;on&#8221; padding_top_1=&#8221;30px&#8221; padding_right_1=&#8221;30px&#8221; padding_bottom_1=&#8221;30px&#8221; padding_left_1=&#8221;30px&#8221; padding_top_2=&#8221;30px&#8221; padding_right_2=&#8221;30px&#8221; padding_bottom_2=&#8221;30px&#8221; padding_left_2=&#8221;30px&#8221; use_background_color_gradient_1=&#8221;on&#8221; use_background_color_gradient_2=&#8221;on&#8221; background_color_gradient_start_1=&#8221;rgba(107,67,0,0.05)&#8221; background_color_gradient_start_2=&#8221;rgba(158,97,0,0.08)&#8221; background_color_gradient_end_1=&#8221;rgba(117,81,24,0.07)&#8221; background_color_gradient_end_2=&#8221;rgba(102,66,0,0.1)&#8221; background_color_gradient_type_2=&#8221;radial&#8221; _builder_version=&#8221;3.0.87&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_line_height=&#8221;1.5em&#8221; header_4_font=&#8221;Love Ya Like A Sister||||||||&#8221; header_4_font_size=&#8221;25px&#8221; header_4_text_color=&#8221;#442d00&#8243; header_4_line_height=&#8221;1.8em&#8221; header_6_font_size=&#8221;12px&#8221; header_6_text_color=&#8221;rgba(4,150,75,0.67)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<h4 class=\"vcex-module vcex-heading vcex-heading-plain\"><span class=\"vcex-heading-inner clr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30970\" src=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg\" alt=\"\" width=\"140\" height=\"175\" srcset=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg 240w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia.jpg 500w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>Eunice Maia<\/span><\/h4>\n<h6>Lisboa<\/h6>\n<p>Professora e fundadora da <a href=\"http:\/\/www.mariagranel.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Maria Granel<\/a>, a primeira mercearia biol\u00f3gica, a granel, em Portugal (sem embalagens).<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.87&#8243; text_font=&#8221;||on||||||&#8221; text_font_size=&#8221;16px&#8221; text_text_color=&#8221;#473b00&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;32px|||&#8221;]<\/p>\n<p>O YogurtNest \u00e9 uma cria\u00e7\u00e3o nacional e sustent\u00e1vel, que permite produzir, de forma muito mais econ\u00f3mica, iogurtes muito saborosos e acabar de vez com as embalagens de pl\u00e1stico, l\u00e1 em casa.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_line_height=&#8221;1.5em&#8221; header_4_font=&#8221;Love Ya Like A Sister||||||||&#8221; header_4_font_size=&#8221;25px&#8221; header_4_text_color=&#8221;#442d00&#8243; header_4_line_height=&#8221;1.8em&#8221; header_6_font_size=&#8221;12px&#8221; header_6_text_color=&#8221;rgba(2,135,60,0.67)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<h4 class=\"vcex-module vcex-heading vcex-heading-plain\"><span class=\"vcex-heading-inner clr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30955\" src=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/fernanda-botelho-240x300.jpg\" alt=\"\" width=\"140\" height=\"175\" srcset=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/fernanda-botelho-240x300.jpg 240w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/fernanda-botelho.jpg 500w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>Fernanda Botelho<\/span><\/h4>\n<h6>Sintra<\/h6>\n<p>Formadora, autora de livros sobre plantas medicinais para adultos e crian\u00e7as e blogger em <a href=\"https:\/\/malvasilvestre.blogspot.pt\/\" target=\"_blank\" rel=\"noopener noreferrer\">Malva Silvestre<\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_font=&#8221;||on||||||&#8221; text_font_size=&#8221;16px&#8221; text_text_color=&#8221;#473b00&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;32px|||&#8221;]<\/p>\n<p>O YogurtNest n\u00e3o serve, apenas, para fazer iogurtes. Eu uso-o, tamb\u00e9m, para terminar de cozinhar arroz, estufados e outros pratos. \u00c9, tamb\u00e9m, um objecto bonito, leve e f\u00e1cil de transportar. Desde que uso, regularmente, o YogurtNest tenho poupado no or\u00e7amento c\u00e1 de casa.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row make_equal=&#8221;on&#8221; padding_top_1=&#8221;30px&#8221; padding_right_1=&#8221;30px&#8221; padding_bottom_1=&#8221;30px&#8221; padding_left_1=&#8221;30px&#8221; padding_top_2=&#8221;30px&#8221; padding_right_2=&#8221;30px&#8221; padding_bottom_2=&#8221;30px&#8221; padding_left_2=&#8221;30px&#8221; use_background_color_gradient_1=&#8221;on&#8221; use_background_color_gradient_2=&#8221;on&#8221; background_color_gradient_start_1=&#8221;rgba(107,67,0,0.05)&#8221; background_color_gradient_start_2=&#8221;rgba(158,97,0,0.08)&#8221; background_color_gradient_end_1=&#8221;rgba(117,81,24,0.07)&#8221; background_color_gradient_end_2=&#8221;rgba(102,66,0,0.1)&#8221; background_color_gradient_type_2=&#8221;radial&#8221; _builder_version=&#8221;3.0.87&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;3.0.92&#8243; text_line_height=&#8221;1.5em&#8221; header_4_font=&#8221;Love Ya Like A Sister||||||||&#8221; header_4_font_size=&#8221;25px&#8221; header_4_text_color=&#8221;#442d00&#8243; header_4_line_height=&#8221;1.8em&#8221; header_6_font_size=&#8221;12px&#8221; header_6_text_color=&#8221;rgba(4,150,75,0.67)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<h4 class=\"vcex-module vcex-heading vcex-heading-plain\"><span class=\"vcex-heading-inner clr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31740\" src=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/joana-silva.jpg\" alt=\"\" width=\"140\" height=\"175\" srcset=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/joana-silva.jpg 374w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/joana-silva-240x300.jpg 240w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>Joana Silva<\/span><\/h4>\n<h6>Sintra<\/h6>\n<p>Farmac\u00eautica de forma\u00e7\u00e3o, m\u00e3e, blogger no <a href=\"http:\/\/justnaturalplease.weebly.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Just Natural Please<\/a> e criadora da <a href=\"http:\/\/justnaturalplease.wixsite.com\/justgranola-shop\" target=\"_blank\" rel=\"noopener noreferrer\">Just Granola Shop<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.87&#8243; text_font=&#8221;||on||||||&#8221; text_font_size=&#8221;16px&#8221; text_text_color=&#8221;#473b00&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;32px|||&#8221;]<\/p>\n<p>\u201cTenho um carinho muito especial pelo meu YogurtNest. Adoro a liberdade de poder fazer os meus iogurtes, de controlar os ingredientes que uso, de poder faz\u00ea-los de forma ecol\u00f3gica e sustent\u00e1vel, sem consumo de energia nem de recipientes descart\u00e1veis. E os iogurtes ficam perfeitos, com \u00f3tima textura e sabor e j\u00e1 s\u00e3o um ingrediente habitual dos pequenos-almo\u00e7os e lanches, c\u00e1 em casa. Formam uma combina\u00e7\u00e3o irresist\u00edvel com as granolas que fa\u00e7o.<\/p>\n<p>E agora, com o beb\u00e9, ainda mais feliz estou por ter um YogurtNest, pois, assim, podemos fazer iogurtes vegetais muito saud\u00e1veis, para ele, e fugir da oferta de mercado, que nem sempre nos agrada.\u201d<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_line_height=&#8221;1.5em&#8221; header_4_font=&#8221;Love Ya Like A Sister||||||||&#8221; header_4_font_size=&#8221;25px&#8221; header_4_text_color=&#8221;#442d00&#8243; header_4_line_height=&#8221;1.8em&#8221; header_6_font_size=&#8221;12px&#8221; header_6_text_color=&#8221;rgba(2,135,60,0.67)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<h4 class=\"vcex-module vcex-heading vcex-heading-plain\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31737\" src=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/raquel-fortes.jpg\" alt=\"\" width=\"140\" height=\"175\" srcset=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/raquel-fortes.jpg 342w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/raquel-fortes-240x300.jpg 240w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>Raquel Fortes<\/h4>\n<h6>Lisboa<\/h6>\n<p>Blogger em It\u2019s Up to You (<a href=\"http:\/\/www.its-uptoyou.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.its-uptoyou.com<\/a>) e consultora na \u00e1rea da promo\u00e7\u00e3o de um estilo de vida saud\u00e1vel, assente numa alimenta\u00e7\u00e3o funcional, na pr\u00e1tica de exerc\u00edcio f\u00edsico e na gest\u00e3o do stress. Co-autora do livro \u201cCrian\u00e7as Saud\u00e1veis, Fam\u00edlias Felizes\u201d.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_font=&#8221;||on||||||&#8221; text_font_size=&#8221;16px&#8221; text_text_color=&#8221;#473b00&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<p>\u201cFoi uma grande surpresa quando conheci o YogurtNest e percebi que \u00e9 poss\u00edvel ter um iogurte cremoso e delicioso em 6 horas, em qualquer lado e sem grandes custos para n\u00f3s e para o planeta. Desde ent\u00e3o, assim como os t\u00e9nis de corrida, a \u201cmochila\u201d gira e pr\u00e1tica do YogurtNest, anda sempre comigo.\u201d<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row make_equal=&#8221;on&#8221; padding_top_1=&#8221;30px&#8221; padding_right_1=&#8221;30px&#8221; padding_bottom_1=&#8221;30px&#8221; padding_left_1=&#8221;30px&#8221; padding_top_2=&#8221;30px&#8221; padding_right_2=&#8221;30px&#8221; padding_bottom_2=&#8221;30px&#8221; padding_left_2=&#8221;30px&#8221; use_background_color_gradient_1=&#8221;on&#8221; use_background_color_gradient_2=&#8221;on&#8221; background_color_gradient_start_1=&#8221;rgba(107,67,0,0.05)&#8221; background_color_gradient_start_2=&#8221;rgba(158,97,0,0.08)&#8221; background_color_gradient_end_1=&#8221;rgba(117,81,24,0.07)&#8221; background_color_gradient_end_2=&#8221;rgba(102,66,0,0.1)&#8221; background_color_gradient_type_2=&#8221;radial&#8221; _builder_version=&#8221;3.0.87&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_line_height=&#8221;1.5em&#8221; header_4_font=&#8221;Love Ya Like A Sister||||||||&#8221; header_4_font_size=&#8221;25px&#8221; header_4_text_color=&#8221;#442d00&#8243; header_4_line_height=&#8221;1.8em&#8221; header_6_font_size=&#8221;12px&#8221; header_6_text_color=&#8221;rgba(4,150,75,0.67)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<h4 class=\"vcex-module vcex-heading vcex-heading-plain\"><span class=\"vcex-heading-inner clr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31788\" src=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/luisa-fortes.jpg\" alt=\"\" width=\"140\" height=\"175\" srcset=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/luisa-fortes.jpg 403w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/luisa-fortes-240x300.jpg 240w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/luisa-fortes-400x503.jpg 400w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>Lu\u00edsa Fortes da Cunha<\/span><\/h4>\n<h6>Carnaxide<\/h6>\n<p>Professora, escritora de livros juvenis e autora do livro \u201cCrian\u00e7as Saud\u00e1veis, Fam\u00edlias Felizes\u201d. Blogger no <a href=\"http:\/\/mycasualbrunch.blogspot.pt\/\" target=\"_blank\" rel=\"noopener noreferrer\">My Casual Brunch<\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_font=&#8221;||on||||||&#8221; text_font_size=&#8221;16px&#8221; text_text_color=&#8221;#473b00&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221; custom_padding=&#8221;20px|||&#8221;]<\/p>\n<p>\u201cO YogurNest permite-me ter iogurtes saud\u00e1veis todos os dias de uma forma simples e pr\u00e1tica. Tem sido uma boa experi\u00eancia!\u201d<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_line_height=&#8221;1.5em&#8221; header_4_font=&#8221;Love Ya Like A Sister||||||||&#8221; header_4_font_size=&#8221;25px&#8221; header_4_text_color=&#8221;#442d00&#8243; header_4_line_height=&#8221;1.8em&#8221; header_6_font_size=&#8221;12px&#8221; header_6_text_color=&#8221;rgba(2,135,60,0.67)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<h4 class=\"vcex-module vcex-heading vcex-heading-plain\"><a href=\"https:\/\/yogurtnest.com\/es\/joana-limao\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31799\" src=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/Joana-Lim\u00e3o.jpg\" alt=\"\" width=\"140\" height=\"172\" srcset=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/Joana-Lim\u00e3o.jpg 404w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/Joana-Lim\u00e3o-244x300.jpg 244w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/><\/a>Joana lim\u00e3o<\/h4>\n<h6>Lisboa<\/h6>\n<p>A Joana gosta do que \u00e9 natural, simples e inteiro. Food e prop stylist, chef privada, criadora de receitas e de menus. Participa, como formadora, em workshops, retiros e aulas de cozinha saud\u00e1vel. Blogger em <a href=\"https:\/\/pleaseconsider.com\/pt-pt\/joana-limao\/\" target=\"_blank\" rel=\"noopener noreferrer\">Please Consider<\/a>\u201d.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_font=&#8221;||on||||||&#8221; text_font_size=&#8221;16px&#8221; text_text_color=&#8221;#473b00&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<p>\u201cO YogurtNest possibilita-me ter iogurtes prontos sem usar energia e em frascos maiores que uma iogurteira normal. Fiquei apaixonada pelo conceito em que as sobras de corti\u00e7a s\u00e3o aproveitadas e os usos s\u00e3o m\u00faltiplos, desde os iogurtes \u00e0 fermenta\u00e7\u00e3o de p\u00e3o ou \u00e0 cozedura lenta de estufados deliciosos. Recomendo!\u201d<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row make_equal=&#8221;on&#8221; padding_top_1=&#8221;30px&#8221; padding_right_1=&#8221;30px&#8221; padding_bottom_1=&#8221;30px&#8221; padding_left_1=&#8221;30px&#8221; padding_top_2=&#8221;30px&#8221; padding_right_2=&#8221;30px&#8221; padding_bottom_2=&#8221;30px&#8221; padding_left_2=&#8221;30px&#8221; use_background_color_gradient_1=&#8221;on&#8221; use_background_color_gradient_2=&#8221;on&#8221; background_color_gradient_start_1=&#8221;rgba(107,67,0,0.05)&#8221; background_color_gradient_start_2=&#8221;rgba(158,97,0,0.08)&#8221; background_color_gradient_end_1=&#8221;rgba(117,81,24,0.07)&#8221; background_color_gradient_end_2=&#8221;rgba(102,66,0,0.1)&#8221; background_color_gradient_type_2=&#8221;radial&#8221; _builder_version=&#8221;3.0.87&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_line_height=&#8221;1.5em&#8221; header_4_font=&#8221;Love Ya Like A Sister||||||||&#8221; header_4_font_size=&#8221;25px&#8221; header_4_text_color=&#8221;#442d00&#8243; header_4_line_height=&#8221;1.8em&#8221; header_6_font_size=&#8221;12px&#8221; header_6_text_color=&#8221;rgba(4,150,75,0.67)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<h4 class=\"vcex-module vcex-heading vcex-heading-plain\"><span class=\"vcex-heading-inner clr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31786\" src=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/cristiano-santos.jpg\" alt=\"\" width=\"140\" height=\"175\" srcset=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/cristiano-santos.jpg 500w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/cristiano-santos-240x300.jpg 240w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>Cristiano Santos<\/span><\/h4>\n<h6>Paredes<\/h6>\n<p><span class=\"fsm fcg\">Artes\u00e3o de mobili\u00e1rio e das colmeias TimberBee; atleta trail runner, duplo vencedor do Grande Trail da Serra de Arga 2017 (Vertical e Sunset 17Km).<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_font=&#8221;||on||||||&#8221; text_font_size=&#8221;16px&#8221; text_text_color=&#8221;#473b00&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221; custom_padding=&#8221;20px|||&#8221;]<\/p>\n<p>\u201cTrabalho com as minhas m\u00e3os e os meus bra\u00e7os, logo, uma boa forma f\u00edsica \u00e9 fundamental para o meu modo de vida. Por outro lado, sou atleta desde que me conhe\u00e7o, pelo que a qualidade do iogurte produzido no YogurtNest, integrado numa dieta equilibrada e uma boa dose de actividade f\u00edsica, \u00e9 essencial para a o estilo de vida que fa\u00e7o.<\/p>\n<p>O YogurtNest \u00e9-me muito especial, pois a minha companheira, Susana, trabalhou com o Miguel na cria\u00e7\u00e3o dos primeiros prot\u00f3tipos e tive a oportunidade de acompanhar o processo de desenvolvimento. O YogurtNest permite, \u00e0s fam\u00edlias, pouparem dinheiro e se tornarem mais independentes.\u201d<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_line_height=&#8221;1.5em&#8221; header_4_font=&#8221;Love Ya Like A Sister||||||||&#8221; header_4_font_size=&#8221;25px&#8221; header_4_text_color=&#8221;#442d00&#8243; header_4_line_height=&#8221;1.8em&#8221; header_6_font_size=&#8221;12px&#8221; header_6_text_color=&#8221;rgba(2,135,60,0.67)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221;]<\/p>\n<h4 class=\"vcex-module vcex-heading vcex-heading-plain\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31787\" src=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/goncalo-pais.jpg\" alt=\"\" width=\"140\" height=\"175\" srcset=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/goncalo-pais.jpg 500w, https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/12\/goncalo-pais-240x300.jpg 240w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>Gon\u00e7alo Pais<\/h4>\n<h6>Alg\u00e9s<\/h6>\n<p>Engenheiro, atleta trail runner, <a href=\"http:\/\/roadbook.blogspot.pt\/\" target=\"_blank\" rel=\"noopener noreferrer\">cicloturista<\/a> e membro da Iniciativa de Transi\u00e7\u00e3o de Linda-a-Velha\/Cooperativa Vizinhar.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.0.89&#8243; text_font=&#8221;||on||||||&#8221; text_font_size=&#8221;16px&#8221; text_text_color=&#8221;#473b00&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_layout=&#8221;light&#8221; custom_padding=&#8221;20px|||&#8221;]<\/p>\n<p>\u201cOptei por um estilo de vida mais activo e saud\u00e1vel, tanto pela idade como pelo facto de ter 2 filhos activos, que queria acompanhar. Interessei-me por nutri\u00e7\u00e3o e comecei a fazer desporto com mais frequ\u00eancia. J\u00e1 me deslocava para todo o lado de bicicleta, mas comecei a entusiasmar-me com a corrida em trilhos e n\u00e3o tardava estava a fazer trails de 3 d\u00edgitos. Cedo me apercebi que o que comia, e em que altura do dia comia, era extremamente importante. Encontros felizes com o Miguel Leal e a Ana Jervis, que j\u00e1 conhec\u00edamos, puseram- nos a caminho da YogurtNest. O iogurte \u00e9 um alimento extremamente rico e completo, mas tinha deixado de o consumir pois os de supermercado est\u00e3o cheios de a\u00e7\u00facar e espessantes. Agora fa\u00e7o litros de iogurte por semana, para o pequeno-almo\u00e7o, p\u00f3s-treino, lanches dos mi\u00fados, gelados, em substitui\u00e7\u00e3o de molhos e para temperar saladas. \u00c9 t\u00e3o f\u00e1cil, pr\u00e1tico e pode ficar no corredor ou na sala enquanto as lactobact\u00e9rias trabalham. \u00c9, sem d\u00favida, dos passos mais f\u00e1ceis e pr\u00e1ticos para melhorar a nossa alimenta\u00e7\u00e3o.\u201d<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Tribu YogurtNest est\u00e1 constituida por todos nosotros que amamos el Planeta, que intentamos hacer nuestra parte para mantenerlo en las mejores condiciones, que nos preocupamos por la calidad de la comida con que nos alimentamos, que amamos la vida e intentamos vivirla plenamente; que nos gusta hacer las cosas con nuestras manos.<br \/>\n\u00bfTe reconoces como uno de nosotros?<br \/>\nSi es as\u00ed, entonces eres parte de la tribu YogurtNest! \u00a1S\u00e9 muy bienvenido!<br \/>\nEstos son algunos de nuestros campeones, que promueven los valores de YogurtNest a trav\u00e9s de su trabajo y actividades.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-36102","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Tribo YogurtNest - YogurtNest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Tribo YogurtNest - YogurtNest\" \/>\n<meta property=\"og:description\" content=\"La Tribu YogurtNest est\u00e1 constituida por todos nosotros que amamos el Planeta, que intentamos hacer nuestra parte para mantenerlo en las mejores condiciones, que nos preocupamos por la calidad de la comida con que nos alimentamos, que amamos la vida e intentamos vivirla plenamente; que nos gusta hacer las cosas con nuestras manos. \u00bfTe reconoces como uno de nosotros? Si es as\u00ed, entonces eres parte de la tribu YogurtNest! \u00a1S\u00e9 muy bienvenido! Estos son algunos de nuestros campeones, que promueven los valores de YogurtNest a trav\u00e9s de su trabajo y actividades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/\" \/>\n<meta property=\"og:site_name\" content=\"YogurtNest\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yogurtnest\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-24T15:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/\",\"url\":\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/\",\"name\":\"La Tribo YogurtNest - YogurtNest\",\"isPartOf\":{\"@id\":\"https:\/\/yogurtnest.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg\",\"datePublished\":\"2017-11-15T14:25:42+00:00\",\"dateModified\":\"2019-04-24T15:50:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#primaryimage\",\"url\":\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg\",\"contentUrl\":\"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/yogurtnest.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Tribo YogurtNest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/yogurtnest.com\/es\/#website\",\"url\":\"https:\/\/yogurtnest.com\/es\/\",\"name\":\"YogurtNest\",\"description\":\"Envios ecol\u00f3gicos at\u00e9 48h I dias \u00fateis I PT e Ilhas\",\"publisher\":{\"@id\":\"https:\/\/yogurtnest.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/yogurtnest.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/yogurtnest.com\/es\/#organization\",\"name\":\"YogurtNest\",\"url\":\"https:\/\/yogurtnest.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/yogurtnest.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/10\/logo_nav.png\",\"contentUrl\":\"http:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/10\/logo_nav.png\",\"width\":500,\"height\":429,\"caption\":\"YogurtNest\"},\"image\":{\"@id\":\"https:\/\/yogurtnest.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/yogurtnest\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Tribo YogurtNest - YogurtNest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/","og_locale":"es_ES","og_type":"article","og_title":"La Tribo YogurtNest - YogurtNest","og_description":"La Tribu YogurtNest est\u00e1 constituida por todos nosotros que amamos el Planeta, que intentamos hacer nuestra parte para mantenerlo en las mejores condiciones, que nos preocupamos por la calidad de la comida con que nos alimentamos, que amamos la vida e intentamos vivirla plenamente; que nos gusta hacer las cosas con nuestras manos. \u00bfTe reconoces como uno de nosotros? Si es as\u00ed, entonces eres parte de la tribu YogurtNest! \u00a1S\u00e9 muy bienvenido! Estos son algunos de nuestros campeones, que promueven los valores de YogurtNest a trav\u00e9s de su trabajo y actividades.","og_url":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/","og_site_name":"YogurtNest","article_publisher":"https:\/\/www.facebook.com\/yogurtnest","article_modified_time":"2019-04-24T15:50:48+00:00","og_image":[{"url":"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/","url":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/","name":"La Tribo YogurtNest - YogurtNest","isPartOf":{"@id":"https:\/\/yogurtnest.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#primaryimage"},"image":{"@id":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#primaryimage"},"thumbnailUrl":"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg","datePublished":"2017-11-15T14:25:42+00:00","dateModified":"2019-04-24T15:50:48+00:00","breadcrumb":{"@id":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#primaryimage","url":"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg","contentUrl":"https:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/11\/eunice-maia-240x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/yogurtnest.com\/es\/la-tribo-yogurtnest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/yogurtnest.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Tribo YogurtNest"}]},{"@type":"WebSite","@id":"https:\/\/yogurtnest.com\/es\/#website","url":"https:\/\/yogurtnest.com\/es\/","name":"YogurtNest","description":"Envios ecol\u00f3gicos at\u00e9 48h I dias \u00fateis I PT e Ilhas","publisher":{"@id":"https:\/\/yogurtnest.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yogurtnest.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/yogurtnest.com\/es\/#organization","name":"YogurtNest","url":"https:\/\/yogurtnest.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/yogurtnest.com\/es\/#\/schema\/logo\/image\/","url":"http:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/10\/logo_nav.png","contentUrl":"http:\/\/yogurtnest.com\/wp-content\/uploads\/2017\/10\/logo_nav.png","width":500,"height":429,"caption":"YogurtNest"},"image":{"@id":"https:\/\/yogurtnest.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yogurtnest"]}]}},"_links":{"self":[{"href":"https:\/\/yogurtnest.com\/es\/wp-json\/wp\/v2\/pages\/36102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogurtnest.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/yogurtnest.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/yogurtnest.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yogurtnest.com\/es\/wp-json\/wp\/v2\/comments?post=36102"}],"version-history":[{"count":0,"href":"https:\/\/yogurtnest.com\/es\/wp-json\/wp\/v2\/pages\/36102\/revisions"}],"wp:attachment":[{"href":"https:\/\/yogurtnest.com\/es\/wp-json\/wp\/v2\/media?parent=36102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}